{"id":5559,"count":2,"description":"","link":"https:\/\/boierpathshala.com\/en\/category\/story\/","name":"Story","slug":"story","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Story Archives | Boier Pathshala<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boierpathshala.com\/en\/category\/story\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Story Archives | Boier Pathshala\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boierpathshala.com\/en\/category\/story\/\" \/>\n<meta property=\"og:site_name\" content=\"Boier Pathshala\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boierpathshala.com\/en\/wp-content\/uploads\/2023\/10\/Boier-Pathshala-Light.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@boierpathshala\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/boierpathshala.com\/en\/category\/story\/\",\"url\":\"https:\/\/boierpathshala.com\/en\/category\/story\/\",\"name\":\"Story Archives | Boier Pathshala\",\"isPartOf\":{\"@id\":\"https:\/\/boierpathshala.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/boierpathshala.com\/en\/category\/story\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/boierpathshala.com\/en\/category\/story\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/boierpathshala.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Story\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/boierpathshala.com\/en\/#website\",\"url\":\"https:\/\/boierpathshala.com\/en\/\",\"name\":\"Boier Pathshala\",\"description\":\"PDF Book Read Online Free Download\",\"publisher\":{\"@id\":\"https:\/\/boierpathshala.com\/en\/#organization\"},\"alternateName\":\"boierpathshala.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/boierpathshala.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/boierpathshala.com\/en\/#organization\",\"name\":\"Boier Pathshala\",\"alternateName\":\"\u09ac\u0987\u09df\u09c7\u09b0 \u09aa\u09be\u09a0\u09b6\u09be\u09b2\u09be\",\"url\":\"https:\/\/boierpathshala.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/boierpathshala.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/boierpathshala.com\/en\/wp-content\/uploads\/2023\/10\/Boier-Pathshala-Dark.png\",\"contentUrl\":\"https:\/\/boierpathshala.com\/en\/wp-content\/uploads\/2023\/10\/Boier-Pathshala-Dark.png\",\"width\":500,\"height\":500,\"caption\":\"Boier Pathshala\"},\"image\":{\"@id\":\"https:\/\/boierpathshala.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/boierpathshala\",\"https:\/\/twitter.com\/boierpathshala\",\"https:\/\/www.youtube.com\/channel\/UCZ4Dm991ZBtF6BLXLYXCifA\/\",\"https:\/\/web.facebook.com\/groups\/boierpathshala\/?_rdc=1&_rdr\",\"https:\/\/www.instagram.com\/boierpathshala\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Story Archives | Boier Pathshala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boierpathshala.com\/en\/category\/story\/","og_locale":"en_US","og_type":"article","og_title":"Story Archives | Boier Pathshala","og_url":"https:\/\/boierpathshala.com\/en\/category\/story\/","og_site_name":"Boier Pathshala","og_image":[{"width":500,"height":500,"url":"https:\/\/boierpathshala.com\/en\/wp-content\/uploads\/2023\/10\/Boier-Pathshala-Light.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@boierpathshala","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/boierpathshala.com\/en\/category\/story\/","url":"https:\/\/boierpathshala.com\/en\/category\/story\/","name":"Story Archives | Boier Pathshala","isPartOf":{"@id":"https:\/\/boierpathshala.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/boierpathshala.com\/en\/category\/story\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/boierpathshala.com\/en\/category\/story\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/boierpathshala.com\/en\/"},{"@type":"ListItem","position":2,"name":"Story"}]},{"@type":"WebSite","@id":"https:\/\/boierpathshala.com\/en\/#website","url":"https:\/\/boierpathshala.com\/en\/","name":"Boier Pathshala","description":"PDF Book Read Online Free Download","publisher":{"@id":"https:\/\/boierpathshala.com\/en\/#organization"},"alternateName":"boierpathshala.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boierpathshala.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/boierpathshala.com\/en\/#organization","name":"Boier Pathshala","alternateName":"\u09ac\u0987\u09df\u09c7\u09b0 \u09aa\u09be\u09a0\u09b6\u09be\u09b2\u09be","url":"https:\/\/boierpathshala.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/boierpathshala.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/boierpathshala.com\/en\/wp-content\/uploads\/2023\/10\/Boier-Pathshala-Dark.png","contentUrl":"https:\/\/boierpathshala.com\/en\/wp-content\/uploads\/2023\/10\/Boier-Pathshala-Dark.png","width":500,"height":500,"caption":"Boier Pathshala"},"image":{"@id":"https:\/\/boierpathshala.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/boierpathshala","https:\/\/twitter.com\/boierpathshala","https:\/\/www.youtube.com\/channel\/UCZ4Dm991ZBtF6BLXLYXCifA\/","https:\/\/web.facebook.com\/groups\/boierpathshala\/?_rdc=1&_rdr","https:\/\/www.instagram.com\/boierpathshala\/"]}]}},"_links":{"self":[{"href":"https:\/\/boierpathshala.com\/en\/wp-json\/wp\/v2\/categories\/5559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boierpathshala.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/boierpathshala.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/boierpathshala.com\/en\/wp-json\/wp\/v2\/posts?categories=5559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}