{"id":4961,"count":2,"description":"","link":"https:\/\/boierpathshala.com\/pdf\/tag\/%e0%a6%ae%e0%a6%a4%e0%a6%bf%e0%a6%89%e0%a6%b0-%e0%a6%b0%e0%a6%b9%e0%a6%ae%e0%a6%be%e0%a6%a8-%e0%a6%b0%e0%a7%87%e0%a6%a8%e0%a7%8d%e0%a6%9f%e0%a7%81-%e0%a6%89%e0%a6%87%e0%a6%95%e0%a6%bf%e0%a6%aa\/","name":"\u09ae\u09a4\u09bf\u0989\u09b0 \u09b0\u09b9\u09ae\u09be\u09a8 \u09b0\u09c7\u09a8\u09cd\u099f\u09c1\u00a0\u0989\u0987\u0995\u09bf\u09aa\u09bf\u09a1\u09bf\u09af\u09bc\u09be","slug":"%e0%a6%ae%e0%a6%a4%e0%a6%bf%e0%a6%89%e0%a6%b0-%e0%a6%b0%e0%a6%b9%e0%a6%ae%e0%a6%be%e0%a6%a8-%e0%a6%b0%e0%a7%87%e0%a6%a8%e0%a7%8d%e0%a6%9f%e0%a7%81-%e0%a6%89%e0%a6%87%e0%a6%95%e0%a6%bf%e0%a6%aa","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u09ae\u09a4\u09bf\u0989\u09b0 \u09b0\u09b9\u09ae\u09be\u09a8 \u09b0\u09c7\u09a8\u09cd\u099f\u09c1\u00a0\u0989\u0987\u0995\u09bf\u09aa\u09bf\u09a1\u09bf\u09af\u09bc\u09be Archives | \u09ac\u0987\u09df\u09c7\u09b0 \u09aa\u09be\u09a0\u09b6\u09be\u09b2\u09be<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boierpathshala.com\/pdf\/tag\/\u09ae\u09a4\u09bf\u0989\u09b0-\u09b0\u09b9\u09ae\u09be\u09a8-\u09b0\u09c7\u09a8\u09cd\u099f\u09c1-\u0989\u0987\u0995\u09bf\u09aa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u09ae\u09a4\u09bf\u0989\u09b0 \u09b0\u09b9\u09ae\u09be\u09a8 \u09b0\u09c7\u09a8\u09cd\u099f\u09c1\u00a0\u0989\u0987\u0995\u09bf\u09aa\u09bf\u09a1\u09bf\u09af\u09bc\u09be Archives | \u09ac\u0987\u09df\u09c7\u09b0 \u09aa\u09be\u09a0\u09b6\u09be\u09b2\u09be\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boierpathshala.com\/pdf\/tag\/\u09ae\u09a4\u09bf\u0989\u09b0-\u09b0\u09b9\u09ae\u09be\u09a8-\u09b0\u09c7\u09a8\u09cd\u099f\u09c1-\u0989\u0987\u0995\u09bf\u09aa\/\" \/>\n<meta property=\"og:site_name\" content=\"\u09ac\u0987\u09df\u09c7\u09b0 \u09aa\u09be\u09a0\u09b6\u09be\u09b2\u09be\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boierpathshala.com\/pdf\/wp-content\/uploads\/2023\/10\/Boier-Pathshala-Light.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@boierpathshala\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/boierpathshala.com\/pdf\/tag\/%e0%a6%ae%e0%a6%a4%e0%a6%bf%e0%a6%89%e0%a6%b0-%e0%a6%b0%e0%a6%b9%e0%a6%ae%e0%a6%be%e0%a6%a8-%e0%a6%b0%e0%a7%87%e0%a6%a8%e0%a7%8d%e0%a6%9f%e0%a7%81-%e0%a6%89%e0%a6%87%e0%a6%95%e0%a6%bf%e0%a6%aa\/\",\"url\":\"https:\/\/boierpathshala.com\/pdf\/tag\/%e0%a6%ae%e0%a6%a4%e0%a6%bf%e0%a6%89%e0%a6%b0-%e0%a6%b0%e0%a6%b9%e0%a6%ae%e0%a6%be%e0%a6%a8-%e0%a6%b0%e0%a7%87%e0%a6%a8%e0%a7%8d%e0%a6%9f%e0%a7%81-%e0%a6%89%e0%a6%87%e0%a6%95%e0%a6%bf%e0%a6%aa\/\",\"name\":\"\u09ae\u09a4\u09bf\u0989\u09b0 \u09b0\u09b9\u09ae\u09be\u09a8 \u09b0\u09c7\u09a8\u09cd\u099f\u09c1\u00a0\u0989\u0987\u0995\u09bf\u09aa\u09bf\u09a1\u09bf\u09af\u09bc\u09be Archives | \u09ac\u0987\u09df\u09c7\u09b0 \u09aa\u09be\u09a0\u09b6\u09be\u09b2\u09be\",\"isPartOf\":{\"@id\":\"https:\/\/boierpathshala.com\/pdf\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/boierpathshala.com\/pdf\/tag\/%e0%a6%ae%e0%a6%a4%e0%a6%bf%e0%a6%89%e0%a6%b0-%e0%a6%b0%e0%a6%b9%e0%a6%ae%e0%a6%be%e0%a6%a8-%e0%a6%b0%e0%a7%87%e0%a6%a8%e0%a7%8d%e0%a6%9f%e0%a7%81-%e0%a6%89%e0%a6%87%e0%a6%95%e0%a6%bf%e0%a6%aa\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/boierpathshala.com\/pdf\/tag\/%e0%a6%ae%e0%a6%a4%e0%a6%bf%e0%a6%89%e0%a6%b0-%e0%a6%b0%e0%a6%b9%e0%a6%ae%e0%a6%be%e0%a6%a8-%e0%a6%b0%e0%a7%87%e0%a6%a8%e0%a7%8d%e0%a6%9f%e0%a7%81-%e0%a6%89%e0%a6%87%e0%a6%95%e0%a6%bf%e0%a6%aa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/boierpathshala.com\/pdf\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u09ae\u09a4\u09bf\u0989\u09b0 \u09b0\u09b9\u09ae\u09be\u09a8 \u09b0\u09c7\u09a8\u09cd\u099f\u09c1\u00a0\u0989\u0987\u0995\u09bf\u09aa\u09bf\u09a1\u09bf\u09af\u09bc\u09be\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/boierpathshala.com\/pdf\/#website\",\"url\":\"https:\/\/boierpathshala.com\/pdf\/\",\"name\":\"\u09ac\u0987\u09df\u09c7\u09b0 \u09aa\u09be\u09a0\u09b6\u09be\u09b2\u09be\",\"description\":\"\u09aa\u09bf\u09a1\u09bf\u098f\u09ab \u09ac\u0987 \u09ab\u09cd\u09b0\u09bf \u09a1\u09be\u0989\u09a8\u09b2\u09cb\u09a1\",\"publisher\":{\"@id\":\"https:\/\/boierpathshala.com\/pdf\/#organization\"},\"alternateName\":\"boierpathshala.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/boierpathshala.com\/pdf\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/boierpathshala.com\/pdf\/#organization\",\"name\":\"Boier Pathshala\",\"alternateName\":\"\u09ac\u0987\u09df\u09c7\u09b0 \u09aa\u09be\u09a0\u09b6\u09be\u09b2\u09be\",\"url\":\"https:\/\/boierpathshala.com\/pdf\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/boierpathshala.com\/pdf\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/boierpathshala.com\/pdf\/wp-content\/uploads\/2023\/10\/Boier-Pathshala-Dark.png\",\"contentUrl\":\"https:\/\/boierpathshala.com\/pdf\/wp-content\/uploads\/2023\/10\/Boier-Pathshala-Dark.png\",\"width\":500,\"height\":500,\"caption\":\"Boier Pathshala\"},\"image\":{\"@id\":\"https:\/\/boierpathshala.com\/pdf\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/boierpathshala\",\"https:\/\/twitter.com\/boierpathshala\",\"https:\/\/www.youtube.com\/channel\/UCZ4Dm991ZBtF6BLXLYXCifA\/\",\"https:\/\/web.facebook.com\/groups\/boierpathshala\/?_rdc=1&_rdr\",\"https:\/\/www.instagram.com\/boierpathshala\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u09ae\u09a4\u09bf\u0989\u09b0 \u09b0\u09b9\u09ae\u09be\u09a8 \u09b0\u09c7\u09a8\u09cd\u099f\u09c1\u00a0\u0989\u0987\u0995\u09bf\u09aa\u09bf\u09a1\u09bf\u09af\u09bc\u09be Archives | \u09ac\u0987\u09df\u09c7\u09b0 \u09aa\u09be\u09a0\u09b6\u09be\u09b2\u09be","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boierpathshala.com\/pdf\/tag\/\u09ae\u09a4\u09bf\u0989\u09b0-\u09b0\u09b9\u09ae\u09be\u09a8-\u09b0\u09c7\u09a8\u09cd\u099f\u09c1-\u0989\u0987\u0995\u09bf\u09aa\/","og_locale":"en_US","og_type":"article","og_title":"\u09ae\u09a4\u09bf\u0989\u09b0 \u09b0\u09b9\u09ae\u09be\u09a8 \u09b0\u09c7\u09a8\u09cd\u099f\u09c1\u00a0\u0989\u0987\u0995\u09bf\u09aa\u09bf\u09a1\u09bf\u09af\u09bc\u09be Archives | \u09ac\u0987\u09df\u09c7\u09b0 \u09aa\u09be\u09a0\u09b6\u09be\u09b2\u09be","og_url":"https:\/\/boierpathshala.com\/pdf\/tag\/\u09ae\u09a4\u09bf\u0989\u09b0-\u09b0\u09b9\u09ae\u09be\u09a8-\u09b0\u09c7\u09a8\u09cd\u099f\u09c1-\u0989\u0987\u0995\u09bf\u09aa\/","og_site_name":"\u09ac\u0987\u09df\u09c7\u09b0 \u09aa\u09be\u09a0\u09b6\u09be\u09b2\u09be","og_image":[{"width":500,"height":500,"url":"https:\/\/boierpathshala.com\/pdf\/wp-content\/uploads\/2023\/10\/Boier-Pathshala-Light.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@boierpathshala","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/boierpathshala.com\/pdf\/tag\/%e0%a6%ae%e0%a6%a4%e0%a6%bf%e0%a6%89%e0%a6%b0-%e0%a6%b0%e0%a6%b9%e0%a6%ae%e0%a6%be%e0%a6%a8-%e0%a6%b0%e0%a7%87%e0%a6%a8%e0%a7%8d%e0%a6%9f%e0%a7%81-%e0%a6%89%e0%a6%87%e0%a6%95%e0%a6%bf%e0%a6%aa\/","url":"https:\/\/boierpathshala.com\/pdf\/tag\/%e0%a6%ae%e0%a6%a4%e0%a6%bf%e0%a6%89%e0%a6%b0-%e0%a6%b0%e0%a6%b9%e0%a6%ae%e0%a6%be%e0%a6%a8-%e0%a6%b0%e0%a7%87%e0%a6%a8%e0%a7%8d%e0%a6%9f%e0%a7%81-%e0%a6%89%e0%a6%87%e0%a6%95%e0%a6%bf%e0%a6%aa\/","name":"\u09ae\u09a4\u09bf\u0989\u09b0 \u09b0\u09b9\u09ae\u09be\u09a8 \u09b0\u09c7\u09a8\u09cd\u099f\u09c1\u00a0\u0989\u0987\u0995\u09bf\u09aa\u09bf\u09a1\u09bf\u09af\u09bc\u09be Archives | \u09ac\u0987\u09df\u09c7\u09b0 \u09aa\u09be\u09a0\u09b6\u09be\u09b2\u09be","isPartOf":{"@id":"https:\/\/boierpathshala.com\/pdf\/#website"},"breadcrumb":{"@id":"https:\/\/boierpathshala.com\/pdf\/tag\/%e0%a6%ae%e0%a6%a4%e0%a6%bf%e0%a6%89%e0%a6%b0-%e0%a6%b0%e0%a6%b9%e0%a6%ae%e0%a6%be%e0%a6%a8-%e0%a6%b0%e0%a7%87%e0%a6%a8%e0%a7%8d%e0%a6%9f%e0%a7%81-%e0%a6%89%e0%a6%87%e0%a6%95%e0%a6%bf%e0%a6%aa\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/boierpathshala.com\/pdf\/tag\/%e0%a6%ae%e0%a6%a4%e0%a6%bf%e0%a6%89%e0%a6%b0-%e0%a6%b0%e0%a6%b9%e0%a6%ae%e0%a6%be%e0%a6%a8-%e0%a6%b0%e0%a7%87%e0%a6%a8%e0%a7%8d%e0%a6%9f%e0%a7%81-%e0%a6%89%e0%a6%87%e0%a6%95%e0%a6%bf%e0%a6%aa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/boierpathshala.com\/pdf\/"},{"@type":"ListItem","position":2,"name":"\u09ae\u09a4\u09bf\u0989\u09b0 \u09b0\u09b9\u09ae\u09be\u09a8 \u09b0\u09c7\u09a8\u09cd\u099f\u09c1\u00a0\u0989\u0987\u0995\u09bf\u09aa\u09bf\u09a1\u09bf\u09af\u09bc\u09be"}]},{"@type":"WebSite","@id":"https:\/\/boierpathshala.com\/pdf\/#website","url":"https:\/\/boierpathshala.com\/pdf\/","name":"\u09ac\u0987\u09df\u09c7\u09b0 \u09aa\u09be\u09a0\u09b6\u09be\u09b2\u09be","description":"\u09aa\u09bf\u09a1\u09bf\u098f\u09ab \u09ac\u0987 \u09ab\u09cd\u09b0\u09bf \u09a1\u09be\u0989\u09a8\u09b2\u09cb\u09a1","publisher":{"@id":"https:\/\/boierpathshala.com\/pdf\/#organization"},"alternateName":"boierpathshala.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boierpathshala.com\/pdf\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/boierpathshala.com\/pdf\/#organization","name":"Boier Pathshala","alternateName":"\u09ac\u0987\u09df\u09c7\u09b0 \u09aa\u09be\u09a0\u09b6\u09be\u09b2\u09be","url":"https:\/\/boierpathshala.com\/pdf\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/boierpathshala.com\/pdf\/#\/schema\/logo\/image\/","url":"https:\/\/boierpathshala.com\/pdf\/wp-content\/uploads\/2023\/10\/Boier-Pathshala-Dark.png","contentUrl":"https:\/\/boierpathshala.com\/pdf\/wp-content\/uploads\/2023\/10\/Boier-Pathshala-Dark.png","width":500,"height":500,"caption":"Boier Pathshala"},"image":{"@id":"https:\/\/boierpathshala.com\/pdf\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/boierpathshala","https:\/\/twitter.com\/boierpathshala","https:\/\/www.youtube.com\/channel\/UCZ4Dm991ZBtF6BLXLYXCifA\/","https:\/\/web.facebook.com\/groups\/boierpathshala\/?_rdc=1&_rdr","https:\/\/www.instagram.com\/boierpathshala\/"]}]}},"_links":{"self":[{"href":"https:\/\/boierpathshala.com\/pdf\/wp-json\/wp\/v2\/tags\/4961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boierpathshala.com\/pdf\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/boierpathshala.com\/pdf\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/boierpathshala.com\/pdf\/wp-json\/wp\/v2\/posts?tags=4961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}